{"id":105616,"date":"2014-11-21T12:11:49","date_gmt":"2014-11-21T10:11:49","guid":{"rendered":"https:\/\/www.mwm.net\/?post_type=reference&#038;p=105616"},"modified":"2025-01-09T12:28:12","modified_gmt":"2025-01-09T10:28:12","slug":"italiana-coke-italia","status":"publish","type":"reference","link":"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/","title":{"rendered":"Italiana Coke, Italia"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.mwm.net\/files\/upload\/image\/5634_2_reference_Italiana_Coke.jpg\" alt=\"La principal coquer\u00eda italiana, Italiana Coke SPA, con cuatro motores de gas TBG 632 V16 MWM\" \/><\/p>\n<h2 class=\"fact-heading\">Datos<\/h2>\n<table class=\"reference-data\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"30%\" \/>\n<col width=\"70%\" \/> <\/colgroup>\n<tbody>\n<tr class=\"odd\">\n<td>Grupo electr\u00f3geno\/motor (R 023):<\/td>\n<td>4 x TBG 632 V16<br \/>\n5 x TCG 2032 V16<\/td>\n<\/tr>\n<tr class=\"even\">\n<td>Segmento\/tipo de gas:<\/td>\n<td>Gas especial\/gas de coque<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td>Cliente:<\/td>\n<td>The Italiana Coke SpA, Italia<\/td>\n<\/tr>\n<tr class=\"even\">\n<td>Potencia total:<\/td>\n<td>25 MW<sub>el<\/sub><\/td>\n<\/tr>\n<tr class=\"odd\">\n<td>Puesta en servicio:<\/td>\n<td>1998 y 2010<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span>La principal coquer\u00eda italiana, Italiana Coke SPA, produce alrededor de 500.000 toneladas de coque al a\u00f1o. Debido a la buena experiencia con los grupos electr\u00f3genos MWM, se sustituyeron cuatro motores antiguos por cuatro unidades TCG 2032 V16 nuevas. MWM tiene una amplia experiencia en la operaci\u00f3n de grupos electr\u00f3genos de gas con gas de coque en todo el mundo.<\/span><\/p>\n<div class=\"pro_grphc\">\n<div class=\"cntct_rght\"><a href=\"https:\/\/www.mwm.net\/es\/contacto\/contacto-con-ventas\/\">Contacto con ventas <strong>Haga clic aqui<\/strong><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La principal coquer\u00eda italiana, Italiana Coke SPA, produce alrededor de 500.000 toneladas de coque al a\u00f1o. Debido a la buena experiencia con los grupos electr\u00f3genos MWM, se sustituyeron cuatro motores antiguos por cuatro unidades TCG 2032 V16 neuvas.<\/p>\n","protected":false},"featured_media":103330,"parent":0,"template":"","meta":{"_acf_changed":false},"application":[1509],"gas_type":[1521],"series":[1562,1564,1577,1578],"power_range__el_":[1529],"country":[1542],"container":[],"class_list":["post-105616","reference","type-reference","status-publish","has-post-thumbnail","hentry","application-planta-de-coquizacion","gas_type-gas-de-horno-de-coque","series-tcg-2032-es","series-tcg-2032-v16-es","series-tbg-632-es","series-tbg-632-v16-es","power_range__el_-hasta-100-000-kw","country-italia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Italiana Coke, Italia - MWM<\/title>\n<meta name=\"description\" content=\"La principal coquer\u00eda italiana, Italiana Coke SPA, produce alrededor de 500.000 toneladas de coque al a\u00f1o. Debido a la buena experiencia con los grupos electr\u00f3genos MWM, se sustituyeron cuatro motores antiguos por cuatro unidades TCG 2032 V16 neuvas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Italiana Coke, Italia\" \/>\n<meta property=\"og:description\" content=\"La principal coquer\u00eda italiana, Italiana Coke SPA, produce alrededor de 500.000 toneladas de coque al a\u00f1o. Debido a la buena experiencia con los grupos electr\u00f3genos MWM, se sustituyeron cuatro motores antiguos por cuatro unidades TCG 2032 V16 neuvas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"MWM\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-09T10:28:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mwm.net\/wp-content\/uploads\/2021\/04\/Unbenannt-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"276\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/aplicaciones-de-gas\\\/referencias\\\/italiana-coke-italia\\\/\",\"url\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/aplicaciones-de-gas\\\/referencias\\\/italiana-coke-italia\\\/\",\"name\":\"Italiana Coke, Italia - MWM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/aplicaciones-de-gas\\\/referencias\\\/italiana-coke-italia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/aplicaciones-de-gas\\\/referencias\\\/italiana-coke-italia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mwm.net\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Unbenannt-1-1.jpg\",\"datePublished\":\"2014-11-21T10:11:49+00:00\",\"dateModified\":\"2025-01-09T10:28:12+00:00\",\"description\":\"La principal coquer\u00eda italiana, Italiana Coke SPA, produce alrededor de 500.000 toneladas de coque al a\u00f1o. Debido a la buena experiencia con los grupos electr\u00f3genos MWM, se sustituyeron cuatro motores antiguos por cuatro unidades TCG 2032 V16 neuvas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/aplicaciones-de-gas\\\/referencias\\\/italiana-coke-italia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mwm.net\\\/es\\\/aplicaciones-de-gas\\\/referencias\\\/italiana-coke-italia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/aplicaciones-de-gas\\\/referencias\\\/italiana-coke-italia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mwm.net\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Unbenannt-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mwm.net\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Unbenannt-1-1.jpg\",\"width\":300,\"height\":276},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/aplicaciones-de-gas\\\/referencias\\\/italiana-coke-italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italiana Coke, Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/\",\"name\":\"MWM\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/#organization\",\"name\":\"Caterpillar Energy Solutions GmbH\",\"url\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mwm.net\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/logo2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mwm.net\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/logo2.jpg\",\"width\":260,\"height\":142,\"caption\":\"Caterpillar Energy Solutions GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mwm.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Italiana Coke, Italia - MWM","description":"La principal coquer\u00eda italiana, Italiana Coke SPA, produce alrededor de 500.000 toneladas de coque al a\u00f1o. Debido a la buena experiencia con los grupos electr\u00f3genos MWM, se sustituyeron cuatro motores antiguos por cuatro unidades TCG 2032 V16 neuvas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/","og_locale":"es_ES","og_type":"article","og_title":"Italiana Coke, Italia","og_description":"La principal coquer\u00eda italiana, Italiana Coke SPA, produce alrededor de 500.000 toneladas de coque al a\u00f1o. Debido a la buena experiencia con los grupos electr\u00f3genos MWM, se sustituyeron cuatro motores antiguos por cuatro unidades TCG 2032 V16 neuvas.","og_url":"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/","og_site_name":"MWM","article_modified_time":"2025-01-09T10:28:12+00:00","og_image":[{"width":300,"height":276,"url":"https:\/\/www.mwm.net\/wp-content\/uploads\/2021\/04\/Unbenannt-1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/","url":"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/","name":"Italiana Coke, Italia - MWM","isPartOf":{"@id":"https:\/\/www.mwm.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/#primaryimage"},"image":{"@id":"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mwm.net\/wp-content\/uploads\/2021\/04\/Unbenannt-1-1.jpg","datePublished":"2014-11-21T10:11:49+00:00","dateModified":"2025-01-09T10:28:12+00:00","description":"La principal coquer\u00eda italiana, Italiana Coke SPA, produce alrededor de 500.000 toneladas de coque al a\u00f1o. Debido a la buena experiencia con los grupos electr\u00f3genos MWM, se sustituyeron cuatro motores antiguos por cuatro unidades TCG 2032 V16 neuvas.","breadcrumb":{"@id":"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/#primaryimage","url":"https:\/\/www.mwm.net\/wp-content\/uploads\/2021\/04\/Unbenannt-1-1.jpg","contentUrl":"https:\/\/www.mwm.net\/wp-content\/uploads\/2021\/04\/Unbenannt-1-1.jpg","width":300,"height":276},{"@type":"BreadcrumbList","@id":"https:\/\/www.mwm.net\/es\/aplicaciones-de-gas\/referencias\/italiana-coke-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mwm.net\/es\/"},{"@type":"ListItem","position":2,"name":"Italiana Coke, Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.mwm.net\/es\/#website","url":"https:\/\/www.mwm.net\/es\/","name":"MWM","description":"","publisher":{"@id":"https:\/\/www.mwm.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mwm.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mwm.net\/es\/#organization","name":"Caterpillar Energy Solutions GmbH","url":"https:\/\/www.mwm.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mwm.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.mwm.net\/wp-content\/uploads\/2026\/08\/logo2.jpg","contentUrl":"https:\/\/www.mwm.net\/wp-content\/uploads\/2026\/08\/logo2.jpg","width":260,"height":142,"caption":"Caterpillar Energy Solutions GmbH"},"image":{"@id":"https:\/\/www.mwm.net\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/reference\/105616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/media\/103330"}],"wp:attachment":[{"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/media?parent=105616"}],"wp:term":[{"taxonomy":"application","embeddable":true,"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/application?post=105616"},{"taxonomy":"gas_type","embeddable":true,"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/gas_type?post=105616"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/series?post=105616"},{"taxonomy":"power_range__el_","embeddable":true,"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/power_range__el_?post=105616"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/country?post=105616"},{"taxonomy":"container","embeddable":true,"href":"https:\/\/www.mwm.net\/es\/wp-json\/wp\/v2\/container?post=105616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}